{"id":2914,"count":1,"description":"","link":"https:\/\/afcindustries.com\/es\/product-category\/carro-de-ordenador-de-quiosco-medico-sobre-guias\/","name":"Carro de ordenador de quiosco m\u00e9dico sobre gu\u00edas","slug":"carro-de-ordenador-de-quiosco-medico-sobre-guias","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/afcindustries.com\/es\/wp-json\/wp\/v2\/product_cat\/2914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afcindustries.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/afcindustries.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/afcindustries.com\/es\/wp-json\/wp\/v2\/product?product_cat=2914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}